{"id":2960,"date":"2026-07-14T21:57:46","date_gmt":"2026-07-15T05:57:46","guid":{"rendered":"https:\/\/cntenaisi.com\/?p=2960"},"modified":"2026-07-14T23:37:30","modified_gmt":"2026-07-15T07:37:30","slug":"da-taxa-de-reducao-de-agua-a-retencao-do-abatimento","status":"publish","type":"post","link":"https:\/\/cntenaisi.com\/pt\/da-taxa-de-reducao-de-agua-a-retencao-do-abatimento\/","title":{"rendered":"Da taxa de redu\u00e7\u00e3o de \u00e1gua \u00e0 reten\u00e7\u00e3o de fluidez: uma an\u00e1lise dos principais indicadores de desempenho do p\u00f3 s\u00f3lido de policarboxilato"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"2960\" class=\"elementor elementor-2960\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a186aff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a186aff\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a337f1c\" data-id=\"a337f1c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20b7c24 elementor-widget elementor-widget-jkit_post_title\" data-id=\"20b7c24\" data-element_type=\"widget\" data-widget_type=\"jkit_post_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-post-title jeg_module___6a57eaf41a564\" ><h1 class=\"post-title style-color\">Da taxa de redu\u00e7\u00e3o de \u00e1gua \u00e0 reten\u00e7\u00e3o de fluidez: uma an\u00e1lise dos principais indicadores de desempenho do p\u00f3 s\u00f3lido de policarboxilato<\/h1><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93e2b10 elementor-widget elementor-widget-post-info\" data-id=\"93e2b10\" data-element_type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-50da504 elementor-inline-item\" itemprop=\"author\">\n\t\t\t\t\t\t<a href=\"https:\/\/cntenaisi.com\/pt\/author\/cntenaisitenessy-com\/\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-user-circle\" viewbox=\"0 0 496 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M248 104c-53 0-96 43-96 96s43 96 96 96 96-43 96-96-43-96-96-96zm0 144c-26.5 0-48-21.5-48-48s21.5-48 48-48 48 21.5 48 48-21.5 48-48 48zm0-240C111 8 0 119 0 256s111 248 248 248 248-111 248-248S385 8 248 8zm0 448c-49.7 0-95.1-18.3-130.1-48.4 14.9-23 40.4-38.6 69.6-39.5 20.8 6.4 40.6 9.6 60.5 9.6s39.7-3.1 60.5-9.6c29.2 1 54.7 16.5 69.6 39.5-35 30.1-80.4 48.4-130.1 48.4zm162.7-84.1c-24.4-31.4-62.1-51.9-105.1-51.9-10.2 0-26 9.6-57.6 9.6-31.5 0-47.4-9.6-57.6-9.6-42.9 0-80.6 20.5-105.1 51.9C61.9 339.2 48 299.2 48 256c0-110.3 89.7-200 200-200s200 89.7 200 200c0 43.2-13.9 83.2-37.3 115.9z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-author\">\n\t\t\t\t\t\t\t\t\t\tTenessy Chemical\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-f6608a9 elementor-inline-item\" itemprop=\"datePublished\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-calendar\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M12 192h424c6.6 0 12 5.4 12 12v260c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V204c0-6.6 5.4-12 12-12zm436-44v-36c0-26.5-21.5-48-48-48h-48V12c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v52H160V12c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v52H48C21.5 64 0 85.5 0 112v36c0 6.6 5.4 12 12 12h424c6.6 0 12-5.4 12-12z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t\t\t\t<time>14 de julho de 2026<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-520c066 elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-clock\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm0 448c-110.5 0-200-89.5-200-200S145.5 56 256 56s200 89.5 200 200-89.5 200-200 200zm61.8-104.4l-84.9-61.7c-3.1-2.3-4.9-5.9-4.9-9.7V116c0-6.6 5.4-12 12-12h32c6.6 0 12 5.4 12 12v141.7l66.8 48.6c5.4 3.9 6.5 11.4 2.6 16.8L334.6 349c-3.9 5.3-11.4 6.5-16.8 2.6z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-time\">\n\t\t\t\t\t\t\t\t\t\t<time>21:57<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba7d947 elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ba7d947\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5e1c138\" data-id=\"5e1c138\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad47495 e-flex e-con-boxed e-con e-parent\" data-id=\"ad47495\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-87cd08a elementor-widget elementor-widget-image\" data-id=\"87cd08a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/cntenaisi.com\/wp-content\/uploads\/2026\/07\/Polycarboxylate-superplasticizers-1024x683.jpg\" class=\"attachment-large size-large wp-image-2968\" alt=\"Superplastificantes de policarboxilato\" srcset=\"https:\/\/cntenaisi.com\/wp-content\/uploads\/2026\/07\/Polycarboxylate-superplasticizers-1024x683.jpg 1024w, https:\/\/cntenaisi.com\/wp-content\/uploads\/2026\/07\/Polycarboxylate-superplasticizers-300x200.jpg 300w, https:\/\/cntenaisi.com\/wp-content\/uploads\/2026\/07\/Polycarboxylate-superplasticizers-768x512.jpg 768w, https:\/\/cntenaisi.com\/wp-content\/uploads\/2026\/07\/Polycarboxylate-superplasticizers-1536x1024.jpg 1536w, https:\/\/cntenaisi.com\/wp-content\/uploads\/2026\/07\/Polycarboxylate-superplasticizers-2048x1365.jpg 2048w, https:\/\/cntenaisi.com\/wp-content\/uploads\/2026\/07\/Polycarboxylate-superplasticizers-18x12.jpg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d938b8e elementor-widget elementor-widget-heading\" data-id=\"d938b8e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Introdu\u00e7\u00e3o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9438598 elementor-widget elementor-widget-text-editor\" data-id=\"9438598\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"ds-markdown-paragraph\"><span class=\"\">No campo dos aditivos para concreto, <span style=\"color: #339966;\"><a style=\"color: #339966;\" href=\"https:\/\/cntenaisi.com\/pt\/produtos\/superplastificante-de-policarboxilato-pce\/\">superplastificantes de policarboxilato<\/a><\/span> tornaram-se um componente essencial e indispens\u00e1vel da tecnologia moderna do concreto, devido \u00e0 sua alta taxa de redu\u00e7\u00e3o de \u00e1gua, ao excelente desempenho na reten\u00e7\u00e3o do abatimento e \u00e0 compatibilidade ambiental. Em compara\u00e7\u00e3o com os superplastificantes l\u00edquidos convencionais \u00e0 base de policarboxilato,\u00a0<\/span><strong><span class=\"\">p\u00f3 s\u00f3lido de policarboxilato<\/span><\/strong><span class=\"\">\u00a0est\u00e1 ganhando cada vez mais aten\u00e7\u00e3o devido \u00e0s suas vantagens em termos de facilidade de transporte, estabilidade de armazenamento e adequa\u00e7\u00e3o a aplica\u00e7\u00f5es especializadas, tais como <span style=\"color: #339966;\"><a style=\"color: #339966;\" href=\"https:\/\/cntenaisi.com\/pt\/aplicativos\/setor-de-construcao\/aditivos-para-argamassa-drymix\/\">argamassas de mistura seca<\/a><\/span> e materiais de inje\u00e7\u00e3o. Este artigo analisar\u00e1 sistematicamente o sistema de \u00edndices-chave de desempenho do p\u00f3 s\u00f3lido de policarboxilato sob a perspectiva da ci\u00eancia dos materiais, desde a taxa de redu\u00e7\u00e3o de \u00e1gua at\u00e9 a reten\u00e7\u00e3o do abatimento.<\/span><\/p><p><!-- notionvc: d8bf0b1a-4a7c-441e-ad32-605d494701bc --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-314f3f2 elementor-widget elementor-widget-heading\" data-id=\"314f3f2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">I. \u00cdndice de redu\u00e7\u00e3o de \u00e1gua: o principal par\u00e2metro de refer\u00eancia para o desempenho de dispers\u00e3o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd7682e elementor-widget elementor-widget-text-editor\" data-id=\"dd7682e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"ds-markdown-paragraph\"><span class=\"\">O\u00a0<\/span><strong><span class=\"\">taxa de redu\u00e7\u00e3o de \u00e1gua<\/span><\/strong><span class=\"\">\u00a0\u00e9 a m\u00e9trica de desempenho mais fundamental para avaliar o policarboxilato em p\u00f3, refletindo a capacidade de dispers\u00e3o do aditivo em rela\u00e7\u00e3o \u00e0s part\u00edculas de cimento. De acordo com a norma nacional GB 8076-2008, a taxa de redu\u00e7\u00e3o de \u00e1gua \u00e9 calculada comparando-se o consumo de \u00e1gua necess\u00e1rio para atingir o mesmo abatimento entre uma mistura de concreto de refer\u00eancia e uma mistura de concreto de teste contendo o aditivo. O p\u00f3 de policarboxilato s\u00f3lido de alta qualidade pode atingir uma taxa de redu\u00e7\u00e3o de \u00e1gua de 38%\u00b11%, significativamente superior \u00e0 dos superplastificantes convencionais \u00e0 base de naftaleno (normalmente 18%-25%) e dos superplastificantes alif\u00e1ticos (aproximadamente 20%-28%).<\/span><\/p><p class=\"ds-markdown-paragraph\"><span class=\"\">O mecanismo subjacente \u00e0 taxa de redu\u00e7\u00e3o da \u00e1gua decorre do\u00a0<\/span><strong><span class=\"\">estrutura molecular em forma de pente<\/span><\/strong><span class=\"\">\u00a0do policarboxilato: grupos ani\u00f4nicos, como carboxilato e sulfonato, presentes na cadeia principal, s\u00e3o adsorvidos nas superf\u00edcies das part\u00edculas de cimento, provocando repuls\u00e3o eletrost\u00e1tica, enquanto as cadeias laterais de \u00e9ter de polioxietileno se estendem para a fase l\u00edquida, gerando\u00a0<\/span><strong><span class=\"\">efeitos de impedimento est\u00e9rico<\/span><\/strong><span class=\"\">\u00a0que impedem efetivamente a flocula\u00e7\u00e3o das part\u00edculas de cimento. No caso de produtos em p\u00f3 s\u00f3lido, o fato de essa configura\u00e7\u00e3o molecular poder ser totalmente preservada ap\u00f3s a dissolu\u00e7\u00e3o determina diretamente o grau em que a taxa de redu\u00e7\u00e3o de \u00e1gua \u00e9 alcan\u00e7ada.<\/span><\/p><p><!-- notionvc: d8bf0b1a-4a7c-441e-ad32-605d494701bc --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f2750d elementor-widget elementor-widget-heading\" data-id=\"1f2750d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Par\u00e2metros moleculares-chave que afetam a taxa de redu\u00e7\u00e3o da \u00e1gua<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b084c50 elementor-widget elementor-widget-text-editor\" data-id=\"b084c50\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"ds-markdown-paragraph\"><span class=\"\">Do ponto de vista da engenharia molecular, as principais vari\u00e1veis que influenciam a taxa de redu\u00e7\u00e3o da \u00e1gua incluem:<\/span><\/p><p class=\"ds-markdown-paragraph\"><strong><span class=\"\">Densidade e comprimento da cadeia lateral<\/span><\/strong><span class=\"\">: A densidade das cadeias laterais de polioxietileno determina a intensidade do efeito de impedimento est\u00e9rico. Normalmente, a taxa de redu\u00e7\u00e3o de \u00e1gua atinge um equil\u00edbrio ideal quando a densidade das cadeias laterais est\u00e1 na faixa de 25% a 35% \u2014 uma densidade excessivamente alta das cadeias laterais reduz a propor\u00e7\u00e3o de grupos de ancoragem da estrutura principal, enfraquecendo a ades\u00e3o \u00e0s part\u00edculas de cimento; cadeias laterais excessivamente curtas proporcionam impedimento est\u00e9rico insuficiente, enquanto cadeias excessivamente longas s\u00e3o propensas a emaranhamento entre si, o que, por sua vez, reduz a efici\u00eancia de dispers\u00e3o.<\/span><\/p><p class=\"ds-markdown-paragraph\"><strong><span class=\"\">Peso molecular e distribui\u00e7\u00e3o<\/span><\/strong><span class=\"\">: O peso molecular m\u00e9dio (Mw) do p\u00f3 s\u00f3lido de policarboxilato \u00e9 normalmente mantido entre 15.000 e 40.000 Da. Quando o peso molecular \u00e9 muito baixo, a camada de adsor\u00e7\u00e3o formada pelas mol\u00e9culas do dispersante na superf\u00edcie das part\u00edculas de cimento fica muito fina, resultando em repuls\u00e3o eletrost\u00e1tica insuficiente; quando \u00e9 muito alto, as dimens\u00f5es moleculares tornam-se excessivas, diminuindo as taxas de difus\u00e3o e tornando as mol\u00e9culas suscet\u00edveis a se enrolarem no ambiente de alta for\u00e7a i\u00f4nica da pasta de cimento, reduzindo assim a adsor\u00e7\u00e3o efetiva. O controle do \u00edndice de polidispers\u00e3o (PDI) na faixa de 1,5 a 2,5 garante que cadeias polim\u00e9ricas de comprimentos variados formem um complemento funcional entre a \u201cdispers\u00e3o inicial\u201d e a \u201cdispers\u00e3o sustentada\u201d.\u201d<\/span><\/p><p class=\"ds-markdown-paragraph\"><span class=\"\">Ao testar a taxa de redu\u00e7\u00e3o de \u00e1gua, \u00e9 necess\u00e1rio um controle rigoroso das condi\u00e7\u00f5es experimentais: temperatura de cura de 20 \u2103 \u00b1 2 \u2103 e umidade \u2265 95%, a fim de garantir a comparabilidade e a reprodutibilidade dos dados. Na pr\u00e1tica, os testes de adaptabilidade cruzada devem ser realizados em combina\u00e7\u00e3o com o tipo de cimento e as caracter\u00edsticas dos aditivos, uma vez que a composi\u00e7\u00e3o mineral de diferentes cimentos (teor de C\u2083A, teor de \u00e1lcalis, etc.) influencia significativamente o comportamento de adsor\u00e7\u00e3o do dispersante.<\/span><\/p><p><!-- notionvc: d8bf0b1a-4a7c-441e-ad32-605d494701bc --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45a030f elementor-widget elementor-widget-heading\" data-id=\"45a030f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">II. Reten\u00e7\u00e3o do abatimento: a garantia fundamental da aplicabilidade da engenharia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d80885 elementor-widget elementor-widget-text-editor\" data-id=\"5d80885\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"ds-markdown-paragraph\"><span class=\"\">Se a taxa de redu\u00e7\u00e3o de \u00e1gua determina a trabalhabilidade inicial do concreto,\u00a0<\/span><strong><span class=\"\">reten\u00e7\u00e3o de assentamento<\/span><\/strong><span class=\"\">\u00a0determina o per\u00edodo durante o qual essa trabalhabilidade pode ser mantida. Trata-se de outro par\u00e2metro essencial para avaliar a qualidade do p\u00f3 de policarboxilato \u2014 especialmente em obras em altas temperaturas e em cen\u00e1rios de transporte de longa dist\u00e2ncia, onde a reten\u00e7\u00e3o do abatimento costuma ter maior import\u00e2ncia pr\u00e1tica do que a taxa inicial de redu\u00e7\u00e3o de \u00e1gua.<\/span><\/p><p class=\"ds-markdown-paragraph\"><span class=\"\">O mecanismo da perda de assentamento ao longo do tempo pode ser compreendido a partir de tr\u00eas aspectos: a hidrata\u00e7\u00e3o do cimento consome \u00e1gua livre e aumenta a viscosidade da pasta; as mol\u00e9culas do dispersante s\u00e3o progressivamente cobertas ou consumidas pelos produtos da hidrata\u00e7\u00e3o; e a temperatura ambiente elevada acelera ambos os processos acima mencionados. A filosofia de projeto do p\u00f3 de policarboxilato com alta reten\u00e7\u00e3o de abatimento visa precisamente esses mecanismos:<\/span><\/p><p class=\"ds-markdown-paragraph\"><strong><span class=\"\">No n\u00edvel do projeto da estrutura molecular<\/span><\/strong><span class=\"\">, a introdu\u00e7\u00e3o de\u00a0<\/span><strong><span class=\"\">grupos funcionais de reten\u00e7\u00e3o de afundamento<\/span><\/strong><span class=\"\">\u00a0tais como grupos \u00e9ster e grupos amida, permite uma hidr\u00f3lise lenta no ambiente alcalino do concreto, liberando continuamente grupos carbox\u00edlicos com capacidade de dispers\u00e3o para obter um \u201caditivo de libera\u00e7\u00e3o lenta\u201d do efeito redutor de \u00e1gua. Pesquisas indicam que o controle do\u00a0<\/span><strong><span class=\"\">rela\u00e7\u00e3o \u00e1cido-\u00e9ter<\/span><\/strong><span class=\"\">\u00a0(a propor\u00e7\u00e3o entre grupos carbox\u00edlicos e cadeias laterais de poli\u00e9ter) \u00e9 fundamental: aumentar a densidade de grupos carbox\u00edlicos pode melhorar a capacidade de adsor\u00e7\u00e3o inicial, mas uma densidade excessiva desses grupos, na verdade, prejudica o desempenho de reten\u00e7\u00e3o do afundamento. Produtos t\u00edpicos de alta reten\u00e7\u00e3o geralmente apresentam uma rela\u00e7\u00e3o \u00e1cido\/\u00e9ter controlada entre 2,5:1 e 4,0:1, enquanto produtos do tipo padr\u00e3o ficam na faixa de 4,5:1 a 6,0:1.<\/span><\/p><p><!-- notionvc: 7b4000ee-b076-4838-a592-7636b2cbdc83 --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab6d436 elementor-widget elementor-widget-heading\" data-id=\"ab6d436\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">M\u00e9todos de avalia\u00e7\u00e3o multidimensional para a reten\u00e7\u00e3o do abatimento<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7206426 elementor-widget elementor-widget-text-editor\" data-id=\"7206426\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"ds-markdown-paragraph\"><span class=\"\">Na pr\u00e1tica da engenharia, a avalia\u00e7\u00e3o da reten\u00e7\u00e3o do abatimento n\u00e3o deve basear-se exclusivamente no indicador isolado da perda de abatimento ao longo do tempo. Um sistema de avalia\u00e7\u00e3o cientificamente mais robusto deve incluir:<\/span><\/p><p class=\"ds-markdown-paragraph\"><strong><span class=\"\">Monitoramento de par\u00e2metros reol\u00f3gicos<\/span><\/strong><span class=\"\">: Utiliza\u00e7\u00e3o de um re\u00f4metro rotacional para medir a tens\u00e3o de escoamento din\u00e2mica e a viscosidade pl\u00e1stica da pasta de cimento ao longo do tempo. Para o p\u00f3 de policarboxilato com excelente desempenho de reten\u00e7\u00e3o de assentamento, o aumento da tens\u00e3o de escoamento ao longo de 120 minutos deve ser inferior a 50% do valor inicial, e a taxa de crescimento da viscosidade pl\u00e1stica n\u00e3o deve exceder 100%. Esse m\u00e9todo \u00e9 mais sens\u00edvel do que o ensaio de afundamento, permitindo a detec\u00e7\u00e3o de deteriora\u00e7\u00e3o reol\u00f3gica que pode passar despercebida \u00e0 observa\u00e7\u00e3o visual.<\/span><\/p><p class=\"ds-markdown-paragraph\"><strong><span class=\"\">Acompanhamento do potencial zeta<\/span><\/strong><span class=\"\">: Utiliza\u00e7\u00e3o de um aparelho de eletroforese para monitorar as varia\u00e7\u00f5es no potencial zeta na superf\u00edcie das part\u00edculas de cimento em fun\u00e7\u00e3o do tempo de hidrata\u00e7\u00e3o. Quando o valor absoluto do potencial zeta permanece acima de -15 mV, a repuls\u00e3o eletrost\u00e1tica \u00e9 suficiente para manter a dispers\u00e3o est\u00e1vel. O objetivo de projeto para dispersantes que mant\u00eam a consist\u00eancia \u00e9 limitar a queda do potencial zeta a n\u00e3o mais do que 30% do valor inicial em 60 minutos.<\/span><\/p><p class=\"ds-markdown-paragraph\"><strong><span class=\"\">Determina\u00e7\u00e3o da quantidade de adsor\u00e7\u00e3o<\/span><\/strong><span class=\"\">: Utiliza\u00e7\u00e3o do m\u00e9todo do carbono org\u00e2nico total (TOC) para medir a quantidade de mol\u00e9culas de dispersante adsorvidas nas part\u00edculas de cimento ao longo do tempo. Um produto ideal para a reten\u00e7\u00e3o do abatimento deve apresentar uma caracter\u00edstica em duas etapas de \u201cadsor\u00e7\u00e3o inicial r\u00e1pida + reposi\u00e7\u00e3o sustentada por libera\u00e7\u00e3o lenta\u201d, em vez de uma atenua\u00e7\u00e3o r\u00e1pida ap\u00f3s uma \u00fanica adsor\u00e7\u00e3o at\u00e9 a satura\u00e7\u00e3o.<\/span><\/p><p class=\"ds-markdown-paragraph\"><span class=\"\">Para aplica\u00e7\u00f5es pr\u00e1ticas de engenharia, o desempenho em termos de reten\u00e7\u00e3o de assentamento do p\u00f3 s\u00f3lido de policarboxilato afeta diretamente a viabilidade de\u00a0<\/span><strong><span class=\"\">transporte de concreto em dist\u00e2ncias ultralongas<\/span><\/strong><span class=\"\">,\u00a0<\/span><strong><span class=\"\">obras na \u00e9poca de altas temperaturas<\/span><\/strong><span class=\"\">, e\u00a0<\/span><strong><span class=\"\">projetos com requisitos especiais de prazo de constru\u00e7\u00e3o, como usinas nucleares e grandes barragens<\/span><\/strong><span class=\"\">. Tomando como exemplo as condi\u00e7\u00f5es de ver\u00e3o, com temperaturas ambientes acima de 35 \u2103, produtos de reten\u00e7\u00e3o de alta qualidade podem controlar a perda de assentamento em at\u00e9 20 mm ao longo de 90 minutos, enquanto produtos comuns podem apresentar perdas superiores a 60 mm nas mesmas condi\u00e7\u00f5es.<\/span><\/p><p><!-- notionvc: 7b4000ee-b076-4838-a592-7636b2cbdc83 --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4c8739 elementor-widget elementor-widget-heading\" data-id=\"e4c8739\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">III. Do estado l\u00edquido ao s\u00f3lido: desafios t\u00e9cnicos na preserva\u00e7\u00e3o do desempenho<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfb1d79 elementor-widget elementor-widget-text-editor\" data-id=\"dfb1d79\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"ds-scroll-area ds-scroll-area--show-on-focus-within ds-scroll-area--enabled _1210dd7 c03cafe9\"><p class=\"ds-markdown-paragraph\"><span class=\"\">A produ\u00e7\u00e3o de p\u00f3 s\u00f3lido de policarboxilato n\u00e3o se resume simplesmente a \u201csecar o l\u00edquido\u201d; o processo de fabrica\u00e7\u00e3o determina diretamente se os indicadores de desempenho mencionados acima podem ser efetivamente mantidos. Atualmente, existem duas principais vias t\u00e9cnicas:<\/span><\/p><p class=\"ds-markdown-paragraph\"><strong><span class=\"\">Secagem por pulveriza\u00e7\u00e3o<\/span><\/strong><span class=\"\">\u00a0\u00e9 o caminho mais direto, mas devido ao\u00a0<\/span><strong><span class=\"\">temperatura de transi\u00e7\u00e3o v\u00edtrea relativamente baixa<\/span><\/strong><span class=\"\">\u00a0No caso dos superplastificantes de policarboxilato (normalmente entre 30 e 50 \u2103), problemas como a ades\u00e3o \u00e0s paredes, a aglomera\u00e7\u00e3o e at\u00e9 mesmo a degrada\u00e7\u00e3o por altas temperaturas tendem a ocorrer durante a secagem, levando a danos na estrutura molecular e \u00e0 deteriora\u00e7\u00e3o do desempenho. Al\u00e9m disso, os efeitos da tens\u00e3o superficial durante a secagem por pulveriza\u00e7\u00e3o podem causar o arranjo orientado das cadeias moleculares, afetando a redispersibilidade do p\u00f3.<\/span><\/p><p class=\"ds-markdown-paragraph\"><strong><span class=\"\">Polimeriza\u00e7\u00e3o em massa<\/span><\/strong><span class=\"\">, por outro lado, parte da s\u00edntese inicial, obtendo produtos s\u00f3lidos diretamente por meio da copolimeriza\u00e7\u00e3o em estado fundido de mon\u00f4meros em um sistema sem solvente. Esse m\u00e9todo oferece vantagens, incluindo alta taxa de convers\u00e3o (acima de 93%), produtos puros e respeito ao meio ambiente, mas imp\u00f5e requisitos mais exigentes quanto \u00e0 sele\u00e7\u00e3o do iniciador, ao controle da temperatura de polimeriza\u00e7\u00e3o e \u00e0 compatibilidade do tipo de macromon\u00f4mero. A s\u00edntese em uma \u00fanica etapa utilizando macromon\u00f4meros representados pelo TPEG (\u00e9ter de polioxietileno de \u00e1lcool al\u00edlico modificado) tornou-se a tend\u00eancia predominante na prepara\u00e7\u00e3o atual de p\u00f3s s\u00f3lidos. Os produtos da polimeriza\u00e7\u00e3o em massa apresentam melhor regularidade estrutural e distribui\u00e7\u00e3o mais uniforme das cadeias laterais, alcan\u00e7ando um equil\u00edbrio superior entre a taxa de redu\u00e7\u00e3o de \u00e1gua e a reten\u00e7\u00e3o de assentamento.<\/span><\/p><\/div><p><!-- notionvc: ff2333b3-3770-414a-9269-1b7f3c354ce6 --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49e9579 elementor-widget elementor-widget-heading\" data-id=\"49e9579\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">IV. Compara\u00e7\u00e3o de desempenho entre produtos em p\u00f3 e l\u00edquidos \u00e0 base de policarboxilato<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e19c14 elementor-widget elementor-widget-text-editor\" data-id=\"6e19c14\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"ds-markdown-paragraph\"><span class=\"\">A tabela a seguir compara os produtos em p\u00f3 com os produtos convencionais \u00e0 base de policarboxilato l\u00edquido em v\u00e1rios aspectos:<\/span><\/p><div class=\"ds-scroll-area ds-scroll-area--show-on-focus-within ds-scroll-area--enabled _1210dd7 c03cafe9\"><table><thead><tr><th><span class=\"\">Dimens\u00e3o de compara\u00e7\u00e3o<\/span><\/th><th><span class=\"\">P\u00f3 s\u00f3lido de policarboxilato<\/span><\/th><th><span class=\"\">Produto l\u00edquido \u00e0 base de policarboxilato<\/span><\/th><\/tr><\/thead><tbody><tr><td><span class=\"\">Conte\u00fado ativo<\/span><\/td><td><span class=\"\">\u226596%<\/span><\/td><td><span class=\"\">40%\u00b12%<\/span><\/td><\/tr><tr><td><span class=\"\">Custo de transporte<\/span><\/td><td><span class=\"\">Baixo (componente sem \u00e1gua)<\/span><\/td><td><span class=\"\">Alto (cont\u00e9m ~60% de \u00e1gua)<\/span><\/td><\/tr><tr><td><span class=\"\">Estabilidade de armazenamento<\/span><\/td><td><span class=\"\">Boa (\u226524 meses em condi\u00e7\u00f5es frescas e secas)<\/span><\/td><td><span class=\"\">Moderado (prote\u00e7\u00e3o contra o congelamento no inverno, prote\u00e7\u00e3o contra o mofo no ver\u00e3o)<\/span><\/td><\/tr><tr><td><span class=\"\">Taxa de dissolu\u00e7\u00e3o<\/span><\/td><td><span class=\"\">Depende do tamanho das part\u00edculas (60-180s)<\/span><\/td><td><span class=\"\">Dispers\u00e3o instant\u00e2nea<\/span><\/td><\/tr><tr><td><span class=\"\">Faixa de taxa de redu\u00e7\u00e3o de \u00e1gua<\/span><\/td><td><span class=\"\">35%-40%<\/span><\/td><td><span class=\"\">30%-38%<\/span><\/td><\/tr><tr><td><span class=\"\">Reten\u00e7\u00e3o de assentamento<\/span><\/td><td><span class=\"\">Tipos de alta reten\u00e7\u00e3o\/padr\u00e3o personaliz\u00e1veis<\/span><\/td><td><span class=\"\">Tipos de alta reten\u00e7\u00e3o\/padr\u00e3o personaliz\u00e1veis<\/span><\/td><\/tr><tr><td><span class=\"\">Cen\u00e1rios aplic\u00e1veis<\/span><\/td><td><span class=\"\">Argamassas de mistura seca, materiais para inje\u00e7\u00e3o, composi\u00e7\u00e3o de p\u00f3s<\/span><\/td><td><span class=\"\">Concreto pronto, concreto pr\u00e9-misturado<\/span><\/td><\/tr><\/tbody><\/table><\/div><p><!-- notionvc: ff2333b3-3770-414a-9269-1b7f3c354ce6 --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c73fa9 elementor-widget elementor-widget-heading\" data-id=\"4c73fa9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">V. Problemas comuns e solu\u00e7\u00f5es em aplica\u00e7\u00f5es de engenharia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a2a9df elementor-widget elementor-widget-text-editor\" data-id=\"0a2a9df\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"ds-markdown-paragraph\"><span class=\"\">Com base em ampla experi\u00eancia pr\u00e1tica em engenharia, os seguintes problemas t\u00edpicos podem ser encontrados na aplica\u00e7\u00e3o de policarboxilato s\u00f3lido em p\u00f3:<\/span><\/p><p class=\"ds-markdown-paragraph\"><strong><span class=\"\">Aglomera\u00e7\u00e3o do p\u00f3 e dissolu\u00e7\u00e3o incompleta<\/span><\/strong><span class=\"\">: Isso \u00e9 causado principalmente pela umidade excessivamente alta do ambiente de armazenamento ou pela veda\u00e7\u00e3o inadequada da embalagem. As medidas para evitar isso incluem: controlar a umidade relativa do ambiente de armazenamento em \u226460%, utilizar sacos de embalagem compostos com camadas internas de barreira contra umidade e atenuar o aglomeramento leve aumentando o tempo de mistura ou elevando adequadamente o teor de \u00e1gua.<\/span><\/p><p class=\"ds-markdown-paragraph\"><strong><span class=\"\">Flutua\u00e7\u00f5es na adaptabilidade com diferentes tipos de cimento<\/span><\/strong><span class=\"\">: As varia\u00e7\u00f5es no teor de C\u2083A e na morfologia do gesso entre diferentes cimentos podem causar flutua\u00e7\u00f5es na taxa de redu\u00e7\u00e3o de \u00e1gua. A contramedida de engenharia consiste em estabelecer um protocolo de \u201cteste por lote\u201d, realizando uma verifica\u00e7\u00e3o pr\u00e9via da compatibilidade do dispersante com o cimento recebido e ajustando a dosagem do p\u00f3 (dentro da faixa de 0,15% a 0,35%), conforme necess\u00e1rio, para compensa\u00e7\u00e3o.<\/span><\/p><p class=\"ds-markdown-paragraph\"><strong><span class=\"\">Reten\u00e7\u00e3o insuficiente do abatimento em condi\u00e7\u00f5es de alta temperatura<\/span><\/strong><span class=\"\">: Para cada aumento de 10 \u2103 na temperatura ambiente, a taxa de hidrata\u00e7\u00e3o do cimento praticamente dobra, aumentando drasticamente o desafio de manter a consist\u00eancia da massa. As solu\u00e7\u00f5es incluem: selecionar um p\u00f3 especializado do tipo retentor com uma rela\u00e7\u00e3o \u00e1cido\/\u00e9ter mais baixa, incorporar quantidades adequadas de componentes retardadores (como gluconato de s\u00f3dio ou sacarose) na composi\u00e7\u00e3o da mistura ou implementar medidas de resfriamento dos agregados.<\/span><\/p><p><!-- notionvc: ff2333b3-3770-414a-9269-1b7f3c354ce6 --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9f8e37 elementor-widget elementor-widget-heading\" data-id=\"e9f8e37\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">VI. Fundamentos da Avalia\u00e7\u00e3o Abrangente de Desempenho e dos Testes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20085f9 elementor-widget elementor-widget-text-editor\" data-id=\"20085f9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"ds-markdown-paragraph\"><span class=\"\">Para avaliar a qualidade global do p\u00f3 de policarboxilato s\u00f3lido, al\u00e9m da taxa de redu\u00e7\u00e3o de \u00e1gua e da reten\u00e7\u00e3o do afundamento, os seguintes aspectos tamb\u00e9m merecem aten\u00e7\u00e3o:<\/span><\/p><ul><li><p class=\"ds-markdown-paragraph\"><strong><span class=\"\">Solubilidade<\/span><\/strong><span class=\"\">: Um p\u00f3 de alta qualidade com tamanho de part\u00edcula de 0,125 mm deve dissolver-se completamente em 60 segundos. Uma dissolu\u00e7\u00e3o excessivamente lenta afeta a efici\u00eancia da mistura no local, enquanto uma dissolu\u00e7\u00e3o excessivamente r\u00e1pida pode causar alta concentra\u00e7\u00e3o localizada, levando ao fen\u00f4meno de \u201csuperdispers\u00e3o\u201d.<\/span><\/p><\/li><li><p class=\"ds-markdown-paragraph\"><strong><span class=\"\">Estabilidade de armazenamento<\/span><\/strong><span class=\"\">: Teor de s\u00f3lidos \u226596%, sem aglomera\u00e7\u00e3o ou deteriora\u00e7\u00e3o da qualidade durante o armazenamento de longo prazo. O monitoramento regular do teor de mat\u00e9ria insol\u00favel e das varia\u00e7\u00f5es no valor do pH permite acompanhar de forma eficaz a degrada\u00e7\u00e3o da qualidade do produto.<\/span><\/p><\/li><li><p class=\"ds-markdown-paragraph\"><strong><span class=\"\">Adaptabilidade<\/span><\/strong><span class=\"\">: A compatibilidade com diferentes marcas de cimento, aditivos minerais (cinza volante, esc\u00f3ria granulada mo\u00edda de alto-forno, p\u00f3 de s\u00edlica, etc.) e agregados afeta diretamente os resultados das aplica\u00e7\u00f5es de engenharia. Recomenda-se realizar pelo menos tr\u00eas s\u00e9ries de ensaios de verifica\u00e7\u00e3o com diferentes combina\u00e7\u00f5es de mat\u00e9rias-primas antes do uso efetivo.<\/span><\/p><\/li><li><p class=\"ds-markdown-paragraph\"><strong><span class=\"\">Indicadores de uniformidade<\/span><\/strong><span class=\"\">: Incluindo o valor do pH (5,5-7,5), o teor de \u00edons cloreto (\u22640,06%), teor de sulfato de s\u00f3dio (\u22645,0%), etc., que devem estar em conformidade com os requisitos das normas GB\/T 8077-2012 e JG\/T 223-2017.<\/span><\/p><\/li><\/ul><p><!-- notionvc: ff2333b3-3770-414a-9269-1b7f3c354ce6 --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ffc0ad elementor-widget elementor-widget-heading\" data-id=\"8ffc0ad\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conclus\u00e3o<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56c1938 elementor-widget elementor-widget-text-editor\" data-id=\"56c1938\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"ds-markdown-paragraph\">Da taxa de redu\u00e7\u00e3o de \u00e1gua \u00e0 reten\u00e7\u00e3o de assentamento, todos os indicadores de desempenho do p\u00f3 s\u00f3lido de policarboxilato t\u00eam origem na sinergia precisa entre sua estrutura molecular e o processo de fabrica\u00e7\u00e3o. A primeira determina a efici\u00eancia econ\u00f4mica e o potencial de resist\u00eancia do material, enquanto o segundo diz respeito \u00e0 flexibilidade das opera\u00e7\u00f5es de constru\u00e7\u00e3o e \u00e0 consist\u00eancia da qualidade da engenharia. Com o desenvolvimento cont\u00ednuo de ferrovias de alta velocidade, projetos hidrel\u00e9tricos, constru\u00e7\u00e3o pr\u00e9-fabricada e outros setores, o mercado de aditivos para concreto registrar\u00e1 uma demanda crescente por produtos de policarboxilato s\u00f3lido de alto desempenho.\u00a0<\/p><p><!-- notionvc: ff2333b3-3770-414a-9269-1b7f3c354ce6 --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a04bf35 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a04bf35\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-335fd9f\" data-id=\"335fd9f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-703cefc elementor-widget__width-auto elementor-widget-mobile__width-initial elementor-widget-tablet__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"703cefc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tTags : \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7320ac6 elementor-widget__width-auto elementor-widget elementor-widget-jkit_post_terms\" data-id=\"7320ac6\" data-element_type=\"widget\" data-widget_type=\"jkit_post_terms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-post-terms jeg_module__1_6a57eaf41f613\" ><span class=\"post-terms\"><span class=\"term-list\"><a href=\"https:\/\/cntenaisi.com\/pt\/etiqueta\/po-de-policarboxilato\/\">p\u00f3 de policarboxilato<\/a><\/span>,<span class=\"term-list\"><a href=\"https:\/\/cntenaisi.com\/pt\/etiqueta\/retencao-de-assentamento\/\">Reten\u00e7\u00e3o de assentamento<\/a><\/span>,<span class=\"term-list\"><a href=\"https:\/\/cntenaisi.com\/pt\/etiqueta\/water-reducing-rate\/\">Taxa de redu\u00e7\u00e3o do consumo de \u00e1gua<\/a><\/span><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d17ceda\" data-id=\"d17ceda\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e156ae8 elementor-widget__width-auto elementor-widget-mobile__width-initial elementor-widget-tablet__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"e156ae8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tCompartilhe isso : \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e61dcf elementor-widget__width-auto jkit-social-shape shape-none elementor-widget elementor-widget-jkit_social_share\" data-id=\"4e61dcf\" data-element_type=\"widget\" data-widget_type=\"jkit_social_share.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-social-share jeg_module__2_6a57eaf4216cc\" ><ul class=\"social-share-list\"><li class=\"elementor-repeater-item-844dad6\" data-social=\"facebook\">\n\t\t\t\t<a href=\"#\" class=\"facebook social-icon\" aria-label=\"compartilhamento social\"><i aria-hidden=\"true\" class=\"jki jki-facebook-light\"><\/i><\/a>\n\t\t\t<\/li><li class=\"elementor-repeater-item-3afceda\" data-social=\"twitter\">\n\t\t\t\t<a href=\"#\" class=\"twitter social-icon\" aria-label=\"compartilhamento social\"><svg viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg><\/a>\n\t\t\t<\/li><li class=\"elementor-repeater-item-b3346a1\" data-social=\"linkedin\">\n\t\t\t\t<a href=\"#\" class=\"linkedin social-icon\" aria-label=\"compartilhamento social\"><svg viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M100.28 448H7.4V148.9h92.88zM53.79 108.1C24.09 108.1 0 83.5 0 53.8a53.79 53.79 0 0 1 107.58 0c0 29.7-24.1 54.3-53.79 54.3zM447.9 448h-92.68V302.4c0-34.7-.7-79.2-48.29-79.2-48.29 0-55.69 37.7-55.69 76.7V448h-92.78V148.9h89.08v40.8h1.3c12.4-23.5 42.69-48.3 87.88-48.3 94 0 111.28 61.9 111.28 142.3V448z\"><\/path><\/svg><\/a>\n\t\t\t<\/li><li class=\"elementor-repeater-item-68544eb\" data-social=\"linkedin\">\n\t\t\t\t<a href=\"#\" class=\"linkedin social-icon\" aria-label=\"compartilhamento social\"><i aria-hidden=\"true\" class=\"jki jki-youtube-v-light\"><\/i><\/a>\n\t\t\t<\/li><\/ul><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d06830b\" data-id=\"d06830b\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1cccbdc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1cccbdc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c5ad621\" data-id=\"c5ad621\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2dcb65e elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"2dcb65e\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tProcurando suporte especializado?\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tEstamos aqui 24 horas por dia, 7 dias por semana.\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjY2MCIsInRvZ2dsZSI6ZmFsc2V9\" target=\"_blank\">\n\t\t\t\t\t\tEntre em contato agora\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f1d8f03 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f1d8f03\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7bf6cb4\" data-id=\"7bf6cb4\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-02d9091 elementor-widget elementor-widget-heading\" data-id=\"02d9091\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Publica\u00e7\u00f5es recentes<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-434bea7 elementor-widget elementor-widget-jkit_post_list\" data-id=\"434bea7\" data-element_type=\"widget\" data-widget_type=\"jkit_post_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-postlist layout-horizontal post-element jkit-pagination-disable jeg_module__3_6a57eaf425711\"  data-id=\"jeg_module__3_6a57eaf425711\" data-settings=\"{&quot;post_type&quot;:&quot;post&quot;,&quot;number_post&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:3,&quot;sizes&quot;:[]},&quot;post_offset&quot;:0,&quot;unique_content&quot;:&quot;disable&quot;,&quot;include_post&quot;:&quot;&quot;,&quot;exclude_post&quot;:&quot;&quot;,&quot;include_category&quot;:&quot;&quot;,&quot;exclude_category&quot;:&quot;&quot;,&quot;include_author&quot;:&quot;&quot;,&quot;include_tag&quot;:&quot;&quot;,&quot;exclude_tag&quot;:&quot;&quot;,&quot;sort_by&quot;:&quot;latest&quot;,&quot;pagination_mode&quot;:&quot;disable&quot;,&quot;pagination_loadmore_text&quot;:&quot;Load More&quot;,&quot;pagination_loading_text&quot;:&quot;Loading...&quot;,&quot;pagination_number_post&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:3,&quot;sizes&quot;:[]},&quot;pagination_scroll_limit&quot;:0,&quot;pagination_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;pagination_icon_position&quot;:&quot;before&quot;,&quot;sg_content_layout&quot;:&quot;horizontal&quot;,&quot;sg_content_image_enable&quot;:&quot;&quot;,&quot;sg_content_background_image_enable&quot;:&quot;&quot;,&quot;sg_content_icon_enable&quot;:&quot;&quot;,&quot;sg_content_icon&quot;:{&quot;value&quot;:&quot;fas fa-circle&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;sg_content_meta_enable&quot;:&quot;yes&quot;,&quot;sg_content_meta_date_enable&quot;:&quot;yes&quot;,&quot;sg_content_meta_date_type&quot;:&quot;published&quot;,&quot;sg_content_meta_date_format&quot;:&quot;default&quot;,&quot;sg_content_meta_date_format_custom&quot;:&quot;F j, Y&quot;,&quot;sg_content_meta_date_icon&quot;:{&quot;value&quot;:&quot;jki jki-calendar-page-empty-light&quot;,&quot;library&quot;:&quot;jkiticon&quot;},&quot;sg_content_meta_category_enable&quot;:&quot;&quot;,&quot;sg_content_meta_category_icon&quot;:{&quot;value&quot;:&quot;fas fa-tag&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;sg_content_meta_position&quot;:&quot;bottom&quot;,&quot;sg_content_image_size_imagesize_size&quot;:&quot;medium&quot;,&quot;paged&quot;:1,&quot;class&quot;:&quot;jkit_post_list&quot;}\"><div class=\"jkit-block-container\"><div class=\"jkit-posts jkit-ajax-flag\">\n            <article class=\"jkit-post post-list-item\">\n                <a href=\"https:\/\/cntenaisi.com\/pt\/da-taxa-de-reducao-de-agua-a-retencao-do-abatimento\/\" >\n                    \n                    <div class=\"jkit-postlist-content\"><span class=\"jkit-postlist-title\">Da taxa de redu\u00e7\u00e3o de \u00e1gua \u00e0 reten\u00e7\u00e3o de fluidez: uma an\u00e1lise dos principais indicadores de desempenho do p\u00f3 s\u00f3lido de policarboxilato<\/span><div class=\"meta-lists\"><span class=\"meta-date\"><i aria-hidden=\"true\" class=\"jki jki-calendar-page-empty-light\"><\/i>14 de julho de 2026<\/span> <\/div><\/div>\n                <\/a>\n            <\/article><article class=\"jkit-post post-list-item\">\n                <a href=\"https:\/\/cntenaisi.com\/pt\/formulacoes-de-argamassa-de-hpmc-com-alta-retencao-de-agua\/\" >\n                    \n                    <div class=\"jkit-postlist-content\"><span class=\"jkit-postlist-title\">T\u00e9cnicas de aplica\u00e7\u00e3o para formula\u00e7\u00f5es de argamassa com HPMC de alta reten\u00e7\u00e3o de \u00e1gua<\/span><div class=\"meta-lists\"><span class=\"meta-date\"><i aria-hidden=\"true\" class=\"jki jki-calendar-page-empty-light\"><\/i>8 de julho de 2026<\/span> <\/div><\/div>\n                <\/a>\n            <\/article><article class=\"jkit-post post-list-item\">\n                <a href=\"https:\/\/cntenaisi.com\/pt\/c1-c2-classificacao-de-adesivos-para-azulejos-explicacao-detalhada-dos-requisitos-dos-diferentes-graus-de-resistencia-para-o-po-de-polimero-redispersavel\/\" >\n                    \n                    <div class=\"jkit-postlist-content\"><span class=\"jkit-postlist-title\">Classifica\u00e7\u00e3o do adesivo para azulejos C1\/C2: Explica\u00e7\u00e3o detalhada dos requisitos dos diferentes graus de resist\u00eancia para o p\u00f3 de pol\u00edmero redispers\u00e1vel<\/span><div class=\"meta-lists\"><span class=\"meta-date\"><i aria-hidden=\"true\" class=\"jki jki-calendar-page-empty-light\"><\/i>29 de junho de 2026<\/span> <\/div><\/div>\n                <\/a>\n            <\/article>\n        <\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-46b7b20 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"46b7b20\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-48692c9\" data-id=\"48692c9\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ebda81c elementor-widget elementor-widget-heading\" data-id=\"ebda81c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Produtos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b549ee2 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b549ee2\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cntenaisi.com\/pt\/produtos\/hidroxipropilmetilcelulose-hpmc\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">HPMC - Hidroxipropilmetilcelulose<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cntenaisi.com\/pt\/produtos\/hidroxietilmetilcelulose-hemc\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">HEMC - Hidroxietilmetilcelulose<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cntenaisi.com\/pt\/produtos\/hidroxietilcelulose-hec\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">HEC - Hidroxietilcelulose<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cntenaisi.com\/pt\/produtos\/carboximetilcelulose-cmc\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">CMC - Carboximetilcelulose<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cntenaisi.com\/pt\/produtos\/celulose-polianionica-pac\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">PAC - celulose poliani\u00f4nica<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cntenaisi.com\/pt\/produtos\/carboximetilcelulose-cmc\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">HPS - \u00c9ter hidroxiprop\u00edlico de amido<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cntenaisi.com\/pt\/produtos\/po-de-polimero-redispersivel-rdp\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">RDP - P\u00f3 de pol\u00edmero redispers\u00edvel<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cntenaisi.com\/pt\/produtos\/superplastificante-de-policarboxilato-pce\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Superplastificante de policarboxilato<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cntenaisi.com\/pt\/produtos\/po-hidrofobico-de-silicone-shp\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">P\u00f3 hidrof\u00f3bico de silicone<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cntenaisi.com\/pt\/produtos\/retardador-de-gesso\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Retardador de gesso<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cntenaisi.com\/pt\/produtos\/antiespumante-em-po\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Desespumante em p\u00f3<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>No campo dos aditivos para concreto, os superplastificantes de policarboxilato tornaram-se um componente essencial e indispens\u00e1vel da tecnologia moderna do concreto, devido \u00e0 sua alta taxa de redu\u00e7\u00e3o de \u00e1gua, ao excelente desempenho na reten\u00e7\u00e3o do abatimento e \u00e0 compatibilidade ambiental. <\/p>","protected":false},"author":1,"featured_media":2968,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[45,46,47],"class_list":["post-2960","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-construction","tag-polycarboxylate-powder","tag-slump-retention","tag-water-reducing-rate"],"_links":{"self":[{"href":"https:\/\/cntenaisi.com\/pt\/wp-json\/wp\/v2\/posts\/2960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cntenaisi.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cntenaisi.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cntenaisi.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cntenaisi.com\/pt\/wp-json\/wp\/v2\/comments?post=2960"}],"version-history":[{"count":16,"href":"https:\/\/cntenaisi.com\/pt\/wp-json\/wp\/v2\/posts\/2960\/revisions"}],"predecessor-version":[{"id":2977,"href":"https:\/\/cntenaisi.com\/pt\/wp-json\/wp\/v2\/posts\/2960\/revisions\/2977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cntenaisi.com\/pt\/wp-json\/wp\/v2\/media\/2968"}],"wp:attachment":[{"href":"https:\/\/cntenaisi.com\/pt\/wp-json\/wp\/v2\/media?parent=2960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cntenaisi.com\/pt\/wp-json\/wp\/v2\/categories?post=2960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cntenaisi.com\/pt\/wp-json\/wp\/v2\/tags?post=2960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}