{"id":2767,"date":"2026-05-11T22:44:04","date_gmt":"2026-05-12T06:44:04","guid":{"rendered":"https:\/\/cntenaisi.com\/?p=2767"},"modified":"2026-05-11T22:44:49","modified_gmt":"2026-05-12T06:44:49","slug":"funktionelle-anwendungen-von-polycarboxylat-fliesmitteln-in-fliesenklebern","status":"publish","type":"post","link":"https:\/\/cntenaisi.com\/de\/funktionelle-anwendungen-von-polycarboxylat-fliesmitteln-in-fliesenklebern\/","title":{"rendered":"Funktionelle Anwendungen von Polycarboxylat-Flie\u00dfmitteln in Fliesenklebern"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"2767\" class=\"elementor elementor-2767\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a186aff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a186aff\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a337f1c\" data-id=\"a337f1c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20b7c24 elementor-widget elementor-widget-jkit_post_title\" data-id=\"20b7c24\" data-element_type=\"widget\" data-widget_type=\"jkit_post_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-post-title jeg_module___6a0441a63d5f2\" ><h1 class=\"post-title style-color\">Funktionelle Anwendungen von Polycarboxylat-Flie\u00dfmitteln in Fliesenklebern<\/h1><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba7d947 elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ba7d947\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5e1c138\" data-id=\"5e1c138\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad47495 e-flex e-con-boxed e-con e-parent\" data-id=\"ad47495\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-87cd08a elementor-widget elementor-widget-image\" data-id=\"87cd08a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/cntenaisi.com\/wp-content\/uploads\/2025\/05\/Tile_Adhesive.webp\" class=\"attachment-large size-large wp-image-833\" alt=\"Fliesen_Kleber\" srcset=\"https:\/\/cntenaisi.com\/wp-content\/uploads\/2025\/05\/Tile_Adhesive.webp 800w, https:\/\/cntenaisi.com\/wp-content\/uploads\/2025\/05\/Tile_Adhesive-300x200.webp 300w, https:\/\/cntenaisi.com\/wp-content\/uploads\/2025\/05\/Tile_Adhesive-768x512.webp 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d938b8e elementor-widget elementor-widget-heading\" data-id=\"d938b8e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Einf\u00fchrung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9438598 elementor-widget elementor-widget-text-editor\" data-id=\"9438598\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Im modernen Bauwesen ist die Keramik <span style=\"color: #339966;\"><a style=\"color: #339966;\" href=\"https:\/\/cntenaisi.com\/de\/anwendungen\/baugewerbe\/fliesenkleber\/\">Fliesenkleber<\/a><\/span> haben den traditionellen Zementm\u00f6rtel als bevorzugtes Material f\u00fcr die Verlegung von Fliesen abgel\u00f6st. Mit der Beliebtheit gro\u00dfformatiger Fliesen mit geringer Absorption, wie z. B. polierte Fliesen und mikrokristalline Steine, sind jedoch Aush\u00f6hlungen und das Abfallen von Fliesen zu h\u00e4ufigen Qualit\u00e4tsproblemen geworden.<\/p><p>Um der Marktnachfrage nach h\u00f6herer Haftfestigkeit, besserer Wasserbest\u00e4ndigkeit und verbesserter Haltbarkeit gerecht zu werden, erf\u00e4hrt die Trockenm\u00f6rteltechnologie einen tiefgreifenden Wandel. Im Mittelpunkt dieses Wandels steht das Polycarboxylat-Flie\u00dfmittel, das sich mit seiner einzigartigen Molekularstruktur und seiner herausragenden Leistung zu einem wichtigen Funktionsmaterial f\u00fcr die Verbesserung der Qualit\u00e4t von Fliesenklebern entwickelt hat.<\/p><p>Dieser Artikel enth\u00e4lt eine eingehende Analyse der Anwendungsprinzipien, der funktionellen Vorteile und der besten Praktiken von Polycarboxylat-Flie\u00dfmitteln in Fliesenklebern.<\/p><p><!-- notionvc: d8bf0b1a-4a7c-441e-ad32-605d494701bc --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-314f3f2 elementor-widget elementor-widget-heading\" data-id=\"314f3f2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">I. Mechanismus der Wirkung: Von der elektrostatischen Absto\u00dfung zur sterischen Behinderung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-910521a e-grid e-con-full e-con e-child\" data-id=\"910521a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c5c56b8 elementor-widget elementor-widget-image\" data-id=\"c5c56b8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/cntenaisi.com\/wp-content\/uploads\/2026\/05\/Polycarboxylate-superplasticizers-1024x683.jpg\" class=\"attachment-large size-large wp-image-2775\" alt=\"Polycarboxylat-Superplasticizer\" srcset=\"https:\/\/cntenaisi.com\/wp-content\/uploads\/2026\/05\/Polycarboxylate-superplasticizers-1024x683.jpg 1024w, https:\/\/cntenaisi.com\/wp-content\/uploads\/2026\/05\/Polycarboxylate-superplasticizers-300x200.jpg 300w, https:\/\/cntenaisi.com\/wp-content\/uploads\/2026\/05\/Polycarboxylate-superplasticizers-768x512.jpg 768w, https:\/\/cntenaisi.com\/wp-content\/uploads\/2026\/05\/Polycarboxylate-superplasticizers-1536x1024.jpg 1536w, https:\/\/cntenaisi.com\/wp-content\/uploads\/2026\/05\/Polycarboxylate-superplasticizers-2048x1365.jpg 2048w, https:\/\/cntenaisi.com\/wp-content\/uploads\/2026\/05\/Polycarboxylate-superplasticizers-18x12.jpg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b97afac elementor-widget elementor-widget-text-editor\" data-id=\"b97afac\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"\">Verstehen, warum <span style=\"color: #339966;\"><a style=\"color: #339966;\" href=\"https:\/\/cntenaisi.com\/de\/produkte\/polycarboxylat-fliesmittel-pce\/\">Polycarboxylat-Flie\u00dfmittel<\/a><\/span> gegen\u00fcber herk\u00f6mmlichen naphthalin- oder melaminbasierten Flie\u00dfmitteln auszeichnet, ist ein Blick auf sein molekulares Design erforderlich. Im Gegensatz zu herk\u00f6mmlichen Flie\u00dfmitteln, die sich ausschlie\u00dflich auf\u00a0<\/span><strong><span class=\"\">elektrostatische Absto\u00dfung<\/span><\/strong><span class=\"\">\u00a0Um Zementpartikel zu dispergieren, weist das Polycarboxylatmolek\u00fcl eine einzigartige \u201ckammartige\u201d Struktur auf: ein langes R\u00fcckgrat mit mehreren aktiven Gruppen und nach au\u00dfen gerichteten Seitenketten.<\/span><\/p><p><!-- notionvc: 7b4000ee-b076-4838-a592-7636b2cbdc83 --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd7682e elementor-widget elementor-widget-text-editor\" data-id=\"dd7682e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"ds-markdown-paragraph\"><span class=\"\">Wenn Polycarboxylat-Flie\u00dfmittel in ein Fliesenklebersystem eingebracht werden, kommt es zu den folgenden physikalisch-chemischen Ver\u00e4nderungen:<\/span><\/p><ol start=\"1\"><li><p class=\"ds-markdown-paragraph\"><strong><span class=\"\">Adsorption und Orientierungsausrichtung<\/span><\/strong><span class=\"\">: Das negativ geladene Grundger\u00fcst adsorbiert \u00fcber Ionen- und Wasserstoffbr\u00fcckenbindungen schnell an den positiv geladenen Oberfl\u00e4chen der Zementpartikel.<\/span><\/p><\/li><li><p class=\"ds-markdown-paragraph\"><strong><span class=\"\">Elektrostatische Absto\u00dfung<\/span><\/strong><span class=\"\">: Die Ladung des Ger\u00fcsts bewirkt, dass sich die Zementteilchen gegenseitig absto\u00dfen, wodurch eine Ausflockung verhindert und das in der ausgeflockten Struktur eingeschlossene freie Wasser freigesetzt wird.\u00a0<\/span><strong><span class=\"\">Wasserreduzierung<\/span><\/strong><span class=\"\">.<\/span><\/p><\/li><li><p class=\"ds-markdown-paragraph\"><strong><span class=\"\">Sterische Hinderung<\/span><\/strong><span class=\"\">: Dies ist der Hauptvorteil von Polycarboxylat-Flie\u00dfmitteln. Die langen Seitenketten, die sich in die w\u00e4ssrige L\u00f6sung erstrecken, bilden eine dicke Polymer-\u201cB\u00fcrstenschicht\u201d um jedes Zementteilchen. Wenn sich zwei Partikel n\u00e4hern, erzeugt diese physikalische Barriere eine starke\u00a0<\/span><strong><span class=\"\">sterische Hinderung<\/span><\/strong><span class=\"\">, und verhindert die Agglomeration.<\/span><\/p><\/li><\/ol><p class=\"ds-markdown-paragraph\"><span class=\"\">Dieser doppelte Stabilisierungsmechanismus - elektrostatische Absto\u00dfung und sterische Hinderung - erm\u00f6glicht es dem Polycarboxylat-Flie\u00dfmittel, eine extrem hohe Dispersionseffizienz bei sehr niedriger Dosierung zu erreichen, den Wasserbedarf erheblich zu senken und gleichzeitig die Flie\u00dff\u00e4higkeit der Mischung und die Standfestigkeit zu verbessern.<\/span><\/p><p><!-- notionvc: d8bf0b1a-4a7c-441e-ad32-605d494701bc --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45a030f elementor-widget elementor-widget-heading\" data-id=\"45a030f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">II. Vier wichtige Leistungsdurchbr\u00fcche von Polycarboxylat-Superplasticizer in Fliesenklebern<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fb7e6d elementor-widget elementor-widget-heading\" data-id=\"6fb7e6d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2.1 H\u00f6chste Dichte: Erh\u00f6ht signifikant die Haftfestigkeit<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d45166 elementor-widget elementor-widget-text-editor\" data-id=\"7d45166\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"ds-markdown-paragraph\"><span class=\"\">Die Haftfestigkeit ist ein wichtiger Indikator f\u00fcr die Qualit\u00e4t eines Fliesenklebers. Nach der Zugabe von Polycarboxylat-Flie\u00dfmittel wird der Wasserbedarf des Klebstoffs erheblich reduziert. Ein geringeres Wasser-Zement-Verh\u00e4ltnis bedeutet eine viel geringere Porosit\u00e4t im Fliesenkleber, was zu einer dichteren, geh\u00e4rteten Struktur f\u00fchrt.<\/span><\/p><p class=\"ds-markdown-paragraph\"><span class=\"\">Die Tests zeigen, dass mit steigender Dosierung des Polycarboxylat-Flie\u00dfmittels (z. B. von 0,15% auf 0,3%) sowohl die\u00a0<\/span><strong><span class=\"\">Standard-Haftfestigkeit<\/span><\/strong><span class=\"\">\u00a0und\u00a0<\/span><strong><span class=\"\">Festigkeit der wassergetr\u00e4nkten Verklebung<\/span><\/strong><span class=\"\">\u00a0des Fliesenklebers deutlich erh\u00f6hen. Das bedeutet, dass die Fliesen nicht nur fest verklebt werden, sondern auch in dauerhaft feuchten Umgebungen wie B\u00e4dern und K\u00fcchen sicher haften bleiben.<\/span><\/p><p><!-- notionvc: 7b4000ee-b076-4838-a592-7636b2cbdc83 --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a7249e elementor-widget elementor-widget-heading\" data-id=\"2a7249e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2.2 Verbesserte Leistung: Hitzebest\u00e4ndigkeit und Frost-Tau-Best\u00e4ndigkeit<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22e0823 elementor-widget elementor-widget-text-editor\" data-id=\"22e0823\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"ds-markdown-paragraph\"><span class=\"\">F\u00fcr Au\u00dfenwandfliesen stellen hohe Sommertemperaturen und wiederholte Frost-Tau-Zyklen eine gro\u00dfe Herausforderung dar. Die\u00a0<\/span><strong><span class=\"\">Mikro-Luftporen-Effekt<\/span><\/strong><span class=\"\">\u00a0des Polycarboxylat-Flie\u00dfmittels spielt hier eine entscheidende Rolle.<\/span><\/p><p class=\"ds-markdown-paragraph\"><span class=\"\">Es bringt eine gro\u00dfe Anzahl submikroskopischer, harmloser geschlossener Luftblasen in den Klebstoff ein. Diese Luftblasen wirken wie \u201cLuftkissen\u201d: Bei hohen Temperaturen puffern sie Spannungs\u00e4nderungen ab und verringern Sch\u00e4den durch thermische Ausdehnung; bei niedrigen Temperaturen bieten sie Raum f\u00fcr die Ausdehnung von Wasser beim Gefrieren. Dadurch wird die Haltbarkeit des Fliesenklebers erheblich verbessert.\u00a0<\/span><strong><span class=\"\">W\u00e4rmealterungsbest\u00e4ndigkeit<\/span><\/strong><span class=\"\">\u00a0und\u00a0<\/span><strong><span class=\"\">Frost-Tau-Wechsel-Festigkeit<\/span><\/strong><span class=\"\">.<\/span><\/p><p><!-- notionvc: 7b4000ee-b076-4838-a592-7636b2cbdc83 --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d18f18c elementor-widget elementor-widget-heading\" data-id=\"d18f18c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2.3 Kosteneinsparungen und Effizienzgewinne: Verbesserte Verarbeitbarkeit<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd7ef70 elementor-widget elementor-widget-text-editor\" data-id=\"cd7ef70\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"ds-markdown-paragraph\"><span class=\"\">Polycarboxylat-Flie\u00dfmittel bieten eine extrem hohe Wasserreduktionsrate (typischerweise 20%-25% oder mehr). Bei gleichen Flie\u00dff\u00e4higkeitsanforderungen kann es das Anmachwasser reduzieren oder bei gleichem Wassergehalt die Spachtelleistung des M\u00f6rtels erheblich verbessern.<\/span><\/p><p class=\"ds-markdown-paragraph\"><span class=\"\">Das gibt den Arbeitern ein geschmeidigeres, \u201cbutterartiges\u201d Gef\u00fchl beim Auftragen, bessere\u00a0<\/span><strong><span class=\"\">Rutschfestigkeit<\/span><\/strong><span class=\"\">, schnellere Installationsgeschwindigkeit und geringere physische Belastung. Da die Fr\u00fchfestigkeit verbessert wird, k\u00f6nnen au\u00dferdem die Projektzeitpl\u00e4ne beschleunigt werden.<\/span><\/p><p><!-- notionvc: 7b4000ee-b076-4838-a592-7636b2cbdc83 --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e18f3d elementor-widget elementor-widget-heading\" data-id=\"4e18f3d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2.4 Gr\u00fcn und sicher: Umweltfreundlich und langlebig<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd774ee elementor-widget elementor-widget-text-editor\" data-id=\"bd774ee\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"ds-markdown-paragraph\">Im modernen Bauwesen wird zunehmend Wert auf Umweltstandards gelegt. Polycarboxylat-Flie\u00dfmittel werden ohne den Einsatz von Formaldehyd oder anderen sch\u00e4dlichen Substanzen hergestellt und entsprechen somit den Anforderungen des Umweltschutzes. Au\u00dferdem enth\u00e4lt es keine Chlorsalze und stellt somit kein Korrosionsrisiko f\u00fcr die Stahlbewehrung dar. Durch die Verringerung der Permeabilit\u00e4t wird das Eindringen von Feuchtigkeit und korrosiven Stoffen wirksam verhindert, wodurch die Gesamtlebensdauer verbessert wird.<\/p><p><!-- notionvc: 7b4000ee-b076-4838-a592-7636b2cbdc83 --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4c8739 elementor-widget elementor-widget-heading\" data-id=\"e4c8739\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">III.  Anwendungsrichtlinien: Wie verwendet man Polycarboxylat-Flie\u00dfmittel in Fliesenklebern richtig?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0709bf elementor-widget elementor-widget-text-editor\" data-id=\"a0709bf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"ds-markdown-paragraph\">Trotz seiner \u00fcberlegenen Leistung ist das Polycarboxylat-Flie\u00dfmittel in der Formulierung sehr empfindlich. Auf der Grundlage <span style=\"color: #339966;\"><a style=\"color: #339966;\" href=\"https:\/\/cntenaisi.com\/de\/\">TENESSY<\/a><\/span>\u2018Produktentwicklung und Anwendungserfahrung sind die folgenden Schl\u00fcsselpunkte f\u00fcr eine optimale Leistung von Fliesenklebern von wesentlicher Bedeutung:<\/p><p><!-- notionvc: ff2333b3-3770-414a-9269-1b7f3c354ce6 --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-135c564 elementor-widget elementor-widget-heading\" data-id=\"135c564\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3.1 Auswahl der Form: Die Pulverform ist entscheidend<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfb1d79 elementor-widget elementor-widget-text-editor\" data-id=\"dfb1d79\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"ds-markdown-paragraph\"><span class=\"\">Zur Verwendung in <span style=\"color: #339966;\"><a style=\"color: #339966;\" href=\"https:\/\/cntenaisi.com\/de\/anwendungen\/pce-fur-trockenmortel\/\">Trockenm\u00f6rtel<\/a><\/span> (Fliesenkleber) muss Polycarboxylat-Flie\u00dfmittel enthalten sein\u00a0<\/span><strong><span class=\"\">Pulverform<\/span><\/strong><span class=\"\">. Diese wird durch Verfahren wie die Spr\u00fchtrocknung der fl\u00fcssigen Mutterlauge hergestellt, was zu gleichm\u00e4\u00dfigen Partikeln, niedrigem Feuchtigkeitsgehalt und guter Flie\u00dff\u00e4higkeit f\u00fchrt und das gleichm\u00e4\u00dfige Mischen mit Zement, Sand und anderen pulverf\u00f6rmigen Zus\u00e4tzen erleichtert.<\/span><\/p><p><!-- notionvc: ff2333b3-3770-414a-9269-1b7f3c354ce6 --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfd8ac5 elementor-widget elementor-widget-heading\" data-id=\"dfd8ac5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3.2 Genaue Dosierung: Weniger ist oft mehr<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c2f0cc elementor-widget elementor-widget-text-editor\" data-id=\"9c2f0cc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"ds-markdown-paragraph\"><span class=\"\">Polycarboxylat-Flie\u00dfmittel sind sehr empfindlich. F\u00fcr Fliesenkleber betr\u00e4gt die empfohlene Dosierung in der Regel\u00a0<\/span><strong><span class=\"\">0,15%-0,3%<\/span><\/strong><span class=\"\">\u00a0des gesamten zementhaltigen Materials.<\/span><\/p><p class=\"ds-markdown-paragraph\"><strong><span class=\"\">Wichtige Warnung<\/span><\/strong><span class=\"\">: Ein \u00dcberma\u00df an Flie\u00dfmittel kann zu schwerwiegenden negativen Auswirkungen f\u00fchren, wie z. B.\u00a0<\/span><strong><span class=\"\">starke Retardierung<\/span><\/strong><span class=\"\">\u00a0(der M\u00f6rtel bleibt lange Zeit unausgeh\u00e4rtet),\u00a0<\/span><strong><span class=\"\">Absonderung und Ausbluten<\/span><\/strong><span class=\"\">, und\u00a0<\/span><strong><span class=\"\">Schichtung<\/span><\/strong><span class=\"\">\u00a0- all dies kann die Haftfestigkeit verringern oder sogar zum Versagen der Konstruktion f\u00fchren.<\/span><\/p><p><!-- notionvc: ff2333b3-3770-414a-9269-1b7f3c354ce6 --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5305643 elementor-widget elementor-widget-heading\" data-id=\"5305643\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3.3 Kompatibilit\u00e4t: Komplexe chemische Synergie<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1dd3bb elementor-widget elementor-widget-text-editor\" data-id=\"c1dd3bb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"ds-markdown-paragraph\"><span class=\"\">Fliesenkleber ist ein komplexes Mehrphasensystem, das Zement und F\u00fcllstoffe enth\u00e4lt, <span style=\"color: #339966;\"><a style=\"color: #339966;\" href=\"https:\/\/cntenaisi.com\/de\/produkte\/redispergierbares-polymerpulver-rdp\/\">redispergierbares Polymerpulver<\/a><\/span>, <span style=\"color: #339966;\"><a style=\"color: #339966;\" href=\"https:\/\/cntenaisi.com\/de\/produkte\/hydroxypropylmethylcellulose-hpmc\/\">Zelluloseether (HPMC)<\/a><\/span>, und verschiedene andere Zusatzstoffe.<\/span><\/p><ul><li><p class=\"ds-markdown-paragraph\"><strong><span class=\"\">Gleichgewicht mit Zelluloseethern<\/span><\/strong><span class=\"\">: Celluloseether verdicken und binden Wasser, schlie\u00dfen aber auch Luft ein; Polycarboxylat-Flie\u00dfmittel dispergieren und verringern die Viskosit\u00e4t. Diese beiden Faktoren m\u00fcssen in einem ausgewogenen Verh\u00e4ltnis zueinander stehen, um eine \u00fcberm\u00e4\u00dfige Flie\u00dff\u00e4higkeit zu vermeiden, die zum Verrutschen der Fliesen f\u00fchren k\u00f6nnte.<\/span><\/p><\/li><li><p class=\"ds-markdown-paragraph\"><strong><span class=\"\">Kompatibilit\u00e4t mit Zement<\/span><\/strong><span class=\"\">: Verschiedene Zementmarken und -chargen (insbesondere mit unterschiedlichem C\u2083A-Gehalt) haben unterschiedliche Adsorptionskapazit\u00e4ten f\u00fcr Polycarboxylat-Flie\u00dfmittel. Bei jedem Wechsel der Zementchargen muss eine Kompatibilit\u00e4tspr\u00fcfung durchgef\u00fchrt werden.<\/span><\/p><\/li><\/ul><p><!-- notionvc: ff2333b3-3770-414a-9269-1b7f3c354ce6 --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ea1186 elementor-widget elementor-widget-heading\" data-id=\"8ea1186\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3.4 Gezielte L\u00f6sungen f\u00fcr spezielle Substrate<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-def0489 elementor-widget elementor-widget-text-editor\" data-id=\"def0489\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"ds-markdown-paragraph\"><span class=\"\">F\u00fcr Fliesen mit extrem niedriger Absorption wie z. B.\u00a0<\/span><strong><span class=\"\">polierte Fliesen<\/span><\/strong><span class=\"\">\u00a0und\u00a0<\/span><strong><span class=\"\">vollfl\u00e4chige Feinsteinzeugfliesen<\/span><\/strong><span class=\"\">, Gew\u00f6hnlicher Zementm\u00f6rtel kann nicht eindringen, um eine mechanische Verbindung herzustellen. Durch die Verringerung der Wasserfilmdicke und die Erh\u00f6hung der Pastendichte erm\u00f6glicht das Polycarboxylat-Flie\u00dfmittel dem Fliesenkleber eine festere mechanische Verzahnung mit dem Fliesenuntergrund.<\/span><\/p><p><!-- notionvc: ff2333b3-3770-414a-9269-1b7f3c354ce6 --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87a4b76 elementor-widget elementor-widget-heading\" data-id=\"87a4b76\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Schlussfolgerung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e1e6a6 elementor-widget elementor-widget-text-editor\" data-id=\"7e1e6a6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"ds-markdown-paragraph\"><span class=\"\">Von einem Vertreter der Flie\u00dfmittel der dritten Generation zu einem zentralen Funktionsmaterial in Trockenm\u00f6rteln,\u00a0<\/span><strong><span class=\"\">Polycarboxylat-Flie\u00dfmittel<\/span><\/strong><span class=\"\">\u00a0ist nicht mehr nur ein Favorit der Betonindustrie - es ist zu einem unverzichtbaren\u00a0<\/span><strong><span class=\"\">Motor zur Leistungssteigerung<\/span><\/strong><span class=\"\">\u00a0f\u00fcr hochwertige Fliesenkleber.<\/span><\/p><p class=\"ds-markdown-paragraph\"><span class=\"\">Durch seinen einzigartigen sterischen Hinderungseffekt l\u00f6st es erfolgreich die Probleme der Verarbeitbarkeit von Fliesenklebern bei niedrigen Wasser-Zement-Verh\u00e4ltnissen. Durch die Optimierung der Porenstruktur wird die Haftfestigkeit und Haltbarkeit umfassend verbessert. F\u00fcr Bauunternehmen und Hersteller, die eine au\u00dfergew\u00f6hnliche Qualit\u00e4t anstreben, ist die wissenschaftliche Anwendung der Polycarboxylat-Flie\u00dfmitteltechnologie der entscheidende Weg zur Beseitigung von Hohlstellen und Abplatzungen und zum Eintritt in eine \u00c4ra hochwertiger Fliesenbel\u00e4ge.<\/span><\/p><p><!-- notionvc: b5bf6508-190c-4be3-a46c-5837014ce909 --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a04bf35 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a04bf35\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-335fd9f\" data-id=\"335fd9f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-703cefc elementor-widget__width-auto elementor-widget-mobile__width-initial elementor-widget-tablet__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"703cefc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tTags : \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7320ac6 elementor-widget__width-auto elementor-widget elementor-widget-jkit_post_terms\" data-id=\"7320ac6\" data-element_type=\"widget\" data-widget_type=\"jkit_post_terms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-post-terms jeg_module__1_6a0441a6435ea\" ><span class=\"post-terms\"><span class=\"term-list\">T\u00e4gliche Chemikalien<\/span><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d17ceda\" data-id=\"d17ceda\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e156ae8 elementor-widget__width-auto elementor-widget-mobile__width-initial elementor-widget-tablet__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"e156ae8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tTeilen Sie dies : \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e61dcf elementor-widget__width-auto jkit-social-shape shape-none elementor-widget elementor-widget-jkit_social_share\" data-id=\"4e61dcf\" data-element_type=\"widget\" data-widget_type=\"jkit_social_share.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-social-share jeg_module__2_6a0441a645237\" ><ul class=\"social-share-list\"><li class=\"elementor-repeater-item-844dad6\" data-social=\"facebook\">\n\t\t\t\t<a href=\"#\" class=\"facebook social-icon\" aria-label=\"soziales-teilen\"><i aria-hidden=\"true\" class=\"jki jki-facebook-light\"><\/i><\/a>\n\t\t\t<\/li><li class=\"elementor-repeater-item-3afceda\" data-social=\"twitter\">\n\t\t\t\t<a href=\"#\" class=\"twitter social-icon\" aria-label=\"soziales-teilen\"><svg viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg><\/a>\n\t\t\t<\/li><li class=\"elementor-repeater-item-b3346a1\" data-social=\"linkedin\">\n\t\t\t\t<a href=\"#\" class=\"linkedin social-icon\" aria-label=\"soziales-teilen\"><svg viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M100.28 448H7.4V148.9h92.88zM53.79 108.1C24.09 108.1 0 83.5 0 53.8a53.79 53.79 0 0 1 107.58 0c0 29.7-24.1 54.3-53.79 54.3zM447.9 448h-92.68V302.4c0-34.7-.7-79.2-48.29-79.2-48.29 0-55.69 37.7-55.69 76.7V448h-92.78V148.9h89.08v40.8h1.3c12.4-23.5 42.69-48.3 87.88-48.3 94 0 111.28 61.9 111.28 142.3V448z\"><\/path><\/svg><\/a>\n\t\t\t<\/li><li class=\"elementor-repeater-item-68544eb\" data-social=\"linkedin\">\n\t\t\t\t<a href=\"#\" class=\"linkedin social-icon\" aria-label=\"soziales-teilen\"><i aria-hidden=\"true\" class=\"jki jki-youtube-v-light\"><\/i><\/a>\n\t\t\t<\/li><\/ul><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d06830b\" data-id=\"d06830b\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1cccbdc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1cccbdc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c5ad621\" data-id=\"c5ad621\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2dcb65e elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"2dcb65e\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tSuchen Sie fachkundige Unterst\u00fctzung?\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tWir sind rund um die Uhr f\u00fcr Sie da.\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjY2MCIsInRvZ2dsZSI6ZmFsc2V9\" target=\"_blank\">\n\t\t\t\t\t\tJetzt kontaktieren\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f1d8f03 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f1d8f03\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7bf6cb4\" data-id=\"7bf6cb4\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-02d9091 elementor-widget elementor-widget-heading\" data-id=\"02d9091\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Neueste Beitr\u00e4ge<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-434bea7 elementor-widget elementor-widget-jkit_post_list\" data-id=\"434bea7\" data-element_type=\"widget\" data-widget_type=\"jkit_post_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-postlist layout-horizontal post-element jkit-pagination-disable jeg_module__3_6a0441a648e62\"  data-id=\"jeg_module__3_6a0441a648e62\" data-settings=\"{&quot;post_type&quot;:&quot;post&quot;,&quot;number_post&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:3,&quot;sizes&quot;:[]},&quot;post_offset&quot;:0,&quot;unique_content&quot;:&quot;disable&quot;,&quot;include_post&quot;:&quot;&quot;,&quot;exclude_post&quot;:&quot;&quot;,&quot;include_category&quot;:&quot;&quot;,&quot;exclude_category&quot;:&quot;&quot;,&quot;include_author&quot;:&quot;&quot;,&quot;include_tag&quot;:&quot;&quot;,&quot;exclude_tag&quot;:&quot;&quot;,&quot;sort_by&quot;:&quot;latest&quot;,&quot;pagination_mode&quot;:&quot;disable&quot;,&quot;pagination_loadmore_text&quot;:&quot;Load More&quot;,&quot;pagination_loading_text&quot;:&quot;Loading...&quot;,&quot;pagination_number_post&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:3,&quot;sizes&quot;:[]},&quot;pagination_scroll_limit&quot;:0,&quot;pagination_icon&quot;:{&quot;value&quot;:&quot;&quot;,&quot;library&quot;:&quot;&quot;},&quot;pagination_icon_position&quot;:&quot;before&quot;,&quot;sg_content_layout&quot;:&quot;horizontal&quot;,&quot;sg_content_image_enable&quot;:&quot;&quot;,&quot;sg_content_background_image_enable&quot;:&quot;&quot;,&quot;sg_content_icon_enable&quot;:&quot;&quot;,&quot;sg_content_icon&quot;:{&quot;value&quot;:&quot;fas fa-circle&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;sg_content_meta_enable&quot;:&quot;yes&quot;,&quot;sg_content_meta_date_enable&quot;:&quot;yes&quot;,&quot;sg_content_meta_date_type&quot;:&quot;published&quot;,&quot;sg_content_meta_date_format&quot;:&quot;default&quot;,&quot;sg_content_meta_date_format_custom&quot;:&quot;F j, Y&quot;,&quot;sg_content_meta_date_icon&quot;:{&quot;value&quot;:&quot;jki jki-calendar-page-empty-light&quot;,&quot;library&quot;:&quot;jkiticon&quot;},&quot;sg_content_meta_category_enable&quot;:&quot;&quot;,&quot;sg_content_meta_category_icon&quot;:{&quot;value&quot;:&quot;fas fa-tag&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;sg_content_meta_position&quot;:&quot;bottom&quot;,&quot;sg_content_image_size_imagesize_size&quot;:&quot;medium&quot;,&quot;paged&quot;:1,&quot;class&quot;:&quot;jkit_post_list&quot;}\"><div class=\"jkit-block-container\"><div class=\"jkit-posts jkit-ajax-flag\">\n            <article class=\"jkit-post post-list-item\">\n                <a href=\"https:\/\/cntenaisi.com\/de\/funktionelle-anwendungen-von-polycarboxylat-fliesmitteln-in-fliesenklebern\/\" >\n                    \n                    <div class=\"jkit-postlist-content\"><span class=\"jkit-postlist-title\">Funktionelle Anwendungen von Polycarboxylat-Flie\u00dfmitteln in Fliesenklebern<\/span><div class=\"meta-lists\"><span class=\"meta-date\"><i aria-hidden=\"true\" class=\"jki jki-calendar-page-empty-light\"><\/i>Mai 11, 2026<\/span> <\/div><\/div>\n                <\/a>\n            <\/article><article class=\"jkit-post post-list-item\">\n                <a href=\"https:\/\/cntenaisi.com\/de\/ein-inhaltsstoff-mit-vielen-vorteilen-das-geheimnis-von-hpmc-in-der-hautpflege-zur-verdickung-filmbildung-und-feuchtigkeitszufuhr\/\" >\n                    \n                    <div class=\"jkit-postlist-content\"><span class=\"jkit-postlist-title\">Ein Inhaltsstoff, mehrere Vorteile: Das Geheimnis von HPMC in der Hautpflege zur Verdickung, Filmbildung und Befeuchtung<\/span><div class=\"meta-lists\"><span class=\"meta-date\"><i aria-hidden=\"true\" class=\"jki jki-calendar-page-empty-light\"><\/i>27. April 2026<\/span> <\/div><\/div>\n                <\/a>\n            <\/article><article class=\"jkit-post post-list-item\">\n                <a href=\"https:\/\/cntenaisi.com\/de\/warum-hec-ein-wesentlicher-bestandteil-von-hochleistungs-trockenmorteln-ist\/\" >\n                    \n                    <div class=\"jkit-postlist-content\"><span class=\"jkit-postlist-title\">Warum HEC ein wesentlicher Bestandteil von Hochleistungs-Trockenm\u00f6rteln ist<\/span><div class=\"meta-lists\"><span class=\"meta-date\"><i aria-hidden=\"true\" class=\"jki jki-calendar-page-empty-light\"><\/i>11. April 2026<\/span> <\/div><\/div>\n                <\/a>\n            <\/article>\n        <\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-46b7b20 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"46b7b20\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-48692c9\" data-id=\"48692c9\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ebda81c elementor-widget elementor-widget-heading\" data-id=\"ebda81c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Produkte<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b549ee2 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b549ee2\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cntenaisi.com\/de\/produkte\/hydroxypropylmethylcellulose-hpmc\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">HPMC - Hydroxypropyl Methyl Cellulose<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cntenaisi.com\/de\/produkte\/hydroxyethylmethylzellulose-hemc\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">HEMC - Hydroxyethylmethylzellulose<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cntenaisi.com\/de\/produkte\/hydroxyethylcellulose-hec\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">HEC - Hydroxyethyl-Zellulose<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cntenaisi.com\/de\/produkte\/carboxymethylcellulose-cmc\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">CMC - Carboxymethyl-Zellulose<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cntenaisi.com\/de\/produkte\/polyanionische-cellulose-pac\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">PAC - Polyanionische Cellulose<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cntenaisi.com\/de\/produkte\/carboxymethylcellulose-cmc\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">HPS - Hydroxypropylst\u00e4rkeether<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cntenaisi.com\/de\/produkte\/redispergierbares-polymerpulver-rdp\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">RDP - Redispergierbares Polymer-Pulver<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cntenaisi.com\/de\/produkte\/polycarboxylat-fliesmittel-pce\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Polycarboxylat-Flie\u00dfmittel<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cntenaisi.com\/de\/produkte\/hydrophobes-silikonpulver-shp\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Hydrophobes Silikonpulver<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cntenaisi.com\/de\/produkte\/gipsverzogerer\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Gipsverz\u00f6gerer<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cntenaisi.com\/de\/produkte\/pulverentschaumer\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-alt-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zM140 300h116v70.9c0 10.7 13 16.1 20.5 8.5l114.3-114.9c4.7-4.7 4.7-12.2 0-16.9l-114.3-115c-7.6-7.6-20.5-2.2-20.5 8.5V212H140c-6.6 0-12 5.4-12 12v64c0 6.6 5.4 12 12 12z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pulver-Entsch\u00e4umer<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Im modernen Bauwesen haben keramische Fliesenkleber den traditionellen Zementm\u00f6rtel als bevorzugtes Material f\u00fcr Fliesenbel\u00e4ge abgel\u00f6st. <\/p>","protected":false},"author":1,"featured_media":833,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-2767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-daily-chemicals"],"_links":{"self":[{"href":"https:\/\/cntenaisi.com\/de\/wp-json\/wp\/v2\/posts\/2767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cntenaisi.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cntenaisi.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cntenaisi.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cntenaisi.com\/de\/wp-json\/wp\/v2\/comments?post=2767"}],"version-history":[{"count":16,"href":"https:\/\/cntenaisi.com\/de\/wp-json\/wp\/v2\/posts\/2767\/revisions"}],"predecessor-version":[{"id":2784,"href":"https:\/\/cntenaisi.com\/de\/wp-json\/wp\/v2\/posts\/2767\/revisions\/2784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cntenaisi.com\/de\/wp-json\/wp\/v2\/media\/833"}],"wp:attachment":[{"href":"https:\/\/cntenaisi.com\/de\/wp-json\/wp\/v2\/media?parent=2767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cntenaisi.com\/de\/wp-json\/wp\/v2\/categories?post=2767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cntenaisi.com\/de\/wp-json\/wp\/v2\/tags?post=2767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}